{"id":896,"count":1,"description":"","link":"https:\/\/www.wearwell.com.tw\/wearwell-wp\/ginis0111\/category\/%e9%ab%98%e9%9b%84%e7%be%8e%e9%a3%9f\/","name":"\u9ad8\u96c4\u7f8e\u98df","slug":"%e9%ab%98%e9%9b%84%e7%be%8e%e9%a3%9f","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.wearwell.com.tw\/wearwell-wp\/ginis0111\/wp-json\/wp\/v2\/categories\/896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wearwell.com.tw\/wearwell-wp\/ginis0111\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.wearwell.com.tw\/wearwell-wp\/ginis0111\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.wearwell.com.tw\/wearwell-wp\/ginis0111\/wp-json\/wp\/v2\/posts?categories=896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}